{"id":939,"date":"2022-09-01T08:55:09","date_gmt":"2022-09-01T08:55:09","guid":{"rendered":"https:\/\/solutionaverinfotech.com\/rdigitek\/?page_id=939"},"modified":"2026-02-06T09:58:00","modified_gmt":"2026-02-06T09:58:00","slug":"management-team","status":"publish","type":"page","link":"https:\/\/rdigitek.com\/home\/management-team\/","title":{"rendered":"Management Team"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"939\" class=\"elementor elementor-939\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31482b35 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"31482b35\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-24b5ad8e\" data-id=\"24b5ad8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48572f28 elementor-widget__width-auto de_scroll_animation_no elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"48572f28\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Management Team<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1207c4f1\" data-id=\"1207c4f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ec3c230 de_scroll_animation_no elementor-widget elementor-widget-de-breadcrumb\" data-id=\"6ec3c230\" data-element_type=\"widget\" data-widget_type=\"de-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"breadcrumbs\">\n\t\t\t\t<a href=\"https:\/\/rdigitek.com\/home\" rel=\"nofollow\">Home<\/a>\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67c73883 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"67c73883\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5577c69d\" data-id=\"5577c69d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7613a704 de_scroll_animation_no elementor-widget elementor-widget-image\" data-id=\"7613a704\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9061c12 de_scroll_animation_no elementor-widget elementor-widget-spacer\" data-id=\"9061c12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));-ms-flex-item-align:stretch;align-self:stretch;-ms-flex-negative:0;flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f1d01c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1d01c9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be9d88a\" data-id=\"be9d88a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c5ebdd1 de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"c5ebdd1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Meet Our Team<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-938c596 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"938c596\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-739d499\" data-id=\"739d499\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1da84c7 de_scroll_animation_no elementor-widget elementor-widget-spacer\" data-id=\"1da84c7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58597b6 elementor-view-framed elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top de_scroll_animation_no elementor-widget elementor-widget-icon-box\" data-id=\"58597b6\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/rdigitek.com\/home\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-box.min.css\">\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-user\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tMr. Arshdeep Singh Mundi\t\t\t\t\t<\/span>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMr. Arshdeep Singh was appointed as the Non-Executive Director of the Company during the January, 2016. He is Key executive of Fastway group and executive director in group companies of Fastway and recently there is tie-up between Fastway and Radiant Digitek and he is appointed as Director in Radiant Digitek and now he is providing us his great expertise to the Radiant.\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9032a2\" data-id=\"e9032a2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-234aee3 de_scroll_animation_no elementor-widget elementor-widget-spacer\" data-id=\"234aee3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efcdd7c elementor-view-framed elementor-shape-circle elementor-mobile-position-top elementor-vertical-align-top de_scroll_animation_no elementor-widget elementor-widget-icon-box\" data-id=\"efcdd7c\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-user\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h5 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tMr. Manjot Singh Mann\t\t\t\t\t<\/span>\n\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMr. Manjot Singh Mann is appointed as non-executive Director in the Company during January, 2016. He is the director of Venus county developers Private Limited, Jujhar construction & travelers private Limited etc\u2026\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b08b8ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b08b8ba\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bfbf7d\" data-id=\"1bfbf7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af331b3 de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"af331b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Board of the Company<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ffa8b6 de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"9ffa8b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.8.0 - 30-10-2022 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>The Board of the Company consists of four members out of them 1 are Executive Directors and 2 non-executives which are as follows :<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33b49ca de_scroll_animation_no elementor-widget elementor-widget-text-editor\" data-id=\"33b49ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<table width=\"559\"><tbody><tr><td width=\"64\">#<\/td><td width=\"222\">Name of Directors<\/td><td width=\"273\">Category<\/td><\/tr><tr><td width=\"64\">1<\/td><td width=\"222\">Shri Kapil Arora<\/td><td width=\"273\">Chairman and Managing Director<\/td><\/tr><tr><td width=\"64\">2<\/td><td width=\"222\">Shri Arshdeep Singh<\/td><td width=\"273\">Non-Executive Director<\/td><\/tr><tr><td width=\"64\">3<\/td><td width=\"222\">Shri Manjot Singh Mann<\/td><td width=\"273\">Non-Executive Director<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Management Team Home Meet Our Team Mr. Arshdeep Singh Mundi Mr. Arshdeep Singh was appointed as the Non-Executive Director of the Company during the January, 2016. He is Key executive of Fastway group and executive director in group companies of Fastway and recently there is tie-up between Fastway and Radiant Digitek and he is appointed [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-939","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Management Team - Rdigitek<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rdigitek.com\/home\/management-team\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Management Team - Rdigitek\" \/>\n<meta property=\"og:description\" content=\"Management Team Home Meet Our Team Mr. Arshdeep Singh Mundi Mr. Arshdeep Singh was appointed as the Non-Executive Director of the Company during the January, 2016. He is Key executive of Fastway group and executive director in group companies of Fastway and recently there is tie-up between Fastway and Radiant Digitek and he is appointed [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rdigitek.com\/home\/management-team\/\" \/>\n<meta property=\"og:site_name\" content=\"Rdigitek\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T09:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rdigitek.com\/home\/management-team\/\",\"url\":\"https:\/\/rdigitek.com\/home\/management-team\/\",\"name\":\"Management Team - Rdigitek\",\"isPartOf\":{\"@id\":\"https:\/\/rdigitek.com\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rdigitek.com\/home\/management-team\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rdigitek.com\/home\/management-team\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png\",\"datePublished\":\"2022-09-01T08:55:09+00:00\",\"dateModified\":\"2026-02-06T09:58:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rdigitek.com\/home\/management-team\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rdigitek.com\/home\/management-team\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/rdigitek.com\/home\/management-team\/#primaryimage\",\"url\":\"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png\",\"contentUrl\":\"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rdigitek.com\/home\/management-team\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/rdigitek.com\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Management Team\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rdigitek.com\/home\/#website\",\"url\":\"https:\/\/rdigitek.com\/home\/\",\"name\":\"Rdigitek\",\"description\":\"Digital Cable Television Service\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rdigitek.com\/home\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Management Team - Rdigitek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rdigitek.com\/home\/management-team\/","og_locale":"en_US","og_type":"article","og_title":"Management Team - Rdigitek","og_description":"Management Team Home Meet Our Team Mr. Arshdeep Singh Mundi Mr. Arshdeep Singh was appointed as the Non-Executive Director of the Company during the January, 2016. He is Key executive of Fastway group and executive director in group companies of Fastway and recently there is tie-up between Fastway and Radiant Digitek and he is appointed [&hellip;]","og_url":"https:\/\/rdigitek.com\/home\/management-team\/","og_site_name":"Rdigitek","article_modified_time":"2026-02-06T09:58:00+00:00","og_image":[{"url":"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rdigitek.com\/home\/management-team\/","url":"https:\/\/rdigitek.com\/home\/management-team\/","name":"Management Team - Rdigitek","isPartOf":{"@id":"https:\/\/rdigitek.com\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rdigitek.com\/home\/management-team\/#primaryimage"},"image":{"@id":"https:\/\/rdigitek.com\/home\/management-team\/#primaryimage"},"thumbnailUrl":"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png","datePublished":"2022-09-01T08:55:09+00:00","dateModified":"2026-02-06T09:58:00+00:00","breadcrumb":{"@id":"https:\/\/rdigitek.com\/home\/management-team\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rdigitek.com\/home\/management-team\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/rdigitek.com\/home\/management-team\/#primaryimage","url":"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png","contentUrl":"https:\/\/rdigitek.com\/home\/wp-content\/uploads\/2021\/09\/shape-divider-08.png"},{"@type":"BreadcrumbList","@id":"https:\/\/rdigitek.com\/home\/management-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rdigitek.com\/home\/"},{"@type":"ListItem","position":2,"name":"Management Team"}]},{"@type":"WebSite","@id":"https:\/\/rdigitek.com\/home\/#website","url":"https:\/\/rdigitek.com\/home\/","name":"Rdigitek","description":"Digital Cable Television Service","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rdigitek.com\/home\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/pages\/939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/comments?post=939"}],"version-history":[{"count":9,"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/pages\/939\/revisions"}],"predecessor-version":[{"id":6946,"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/pages\/939\/revisions\/6946"}],"wp:attachment":[{"href":"https:\/\/rdigitek.com\/home\/wp-json\/wp\/v2\/media?parent=939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}